{"id":1164,"date":"2017-02-07T10:46:00","date_gmt":"2017-02-07T09:46:00","guid":{"rendered":"https:\/\/www.rehatechnology.com\/new?page_id=1164"},"modified":"2019-04-26T16:25:42","modified_gmt":"2019-04-26T14:25:42","slug":"laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder","status":"publish","type":"post","link":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/","title":{"rendered":"Laufen lernen in Maulbronn &#8211; Gang-Roboter unterst\u00fctzt gehbehinderte Kinder"},"content":{"rendered":"<p><span id=\"result_box\" class=\"\" lang=\"en\"><span class=\"\">Deutschlandweit hat das Kinderzentrum Maulbronn jetzt den ersten Gang-Roboter einer v\u00f6llig neuen Generation in Betrieb genommen. Das Ger\u00e4t wurde speziell f\u00fcr gehbehinderte Kinder entwickelt und erm\u00f6glicht ganz neue therapeutische M\u00f6glichkeiten.<\/span><\/span><\/p>\n<p><a href=\"https:\/\/kize.eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Besuchen Sie die Webseite des Kinderzentrums Maulbronn<\/a> und erfahren Sie mehr \u00fcber deren Behandlungsmethoden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschlandweit hat das Kinderzentrum Maulbronn jetzt den ersten Gang-Roboter einer v\u00f6llig neuen Generation in Betrieb genommen. Das Ger\u00e4t wurde speziell f\u00fcr gehbehinderte Kinder entwickelt und erm\u00f6glicht ganz neue therapeutische M\u00f6glichkeiten. Besuchen Sie die Webseite des Kinderzentrums Maulbronn und erfahren Sie mehr \u00fcber deren Behandlungsmethoden.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology\" \/>\n<meta property=\"og:description\" content=\"Deutschlandweit hat das Kinderzentrum Maulbronn jetzt den ersten Gang-Roboter einer v\u00f6llig neuen Generation in Betrieb genommen. Das Ger\u00e4t wurde speziell f\u00fcr gehbehinderte Kinder entwickelt und erm\u00f6glicht ganz neue therapeutische M\u00f6glichkeiten. Besuchen Sie die Webseite des Kinderzentrums Maulbronn und erfahren Sie mehr \u00fcber deren Behandlungsmethoden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\" \/>\n<meta property=\"og:site_name\" content=\"Reha Technology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rehatechnology\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-07T09:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-26T14:25:42+00:00\" \/>\n<meta name=\"author\" content=\"Reha Technology\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rehatechnology\" \/>\n<meta name=\"twitter:site\" content=\"@rehatechnology\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reha Technology\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\"},\"author\":{\"name\":\"Reha Technology\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#\/schema\/person\/b5c34ede0f70241218cc551621000dea\"},\"headline\":\"Laufen lernen in Maulbronn &#8211; Gang-Roboter unterst\u00fctzt gehbehinderte Kinder\",\"datePublished\":\"2017-02-07T09:46:00+00:00\",\"dateModified\":\"2019-04-26T14:25:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\",\"url\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\",\"name\":\"Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology\",\"isPartOf\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#website\"},\"datePublished\":\"2017-02-07T09:46:00+00:00\",\"dateModified\":\"2019-04-26T14:25:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.rehatechnology.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laufen lernen in Maulbronn &#8211; Gang-Roboter unterst\u00fctzt gehbehinderte Kinder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#website\",\"url\":\"https:\/\/www.rehatechnology.com\/de\/\",\"name\":\"Reha Technology\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rehatechnology.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#organization\",\"name\":\"Reha Technology\",\"url\":\"https:\/\/www.rehatechnology.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.rehatechnology.com\/wp-content\/uploads\/logo_reha_technology.svg\",\"contentUrl\":\"https:\/\/www.rehatechnology.com\/wp-content\/uploads\/logo_reha_technology.svg\",\"width\":1,\"height\":1,\"caption\":\"Reha Technology\"},\"image\":{\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rehatechnology\/\",\"https:\/\/x.com\/rehatechnology\",\"https:\/\/ch.linkedin.com\/company\/reha-technology-ag\",\"https:\/\/www.youtube.com\/user\/rehatechnology\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rehatechnology.com\/de\/#\/schema\/person\/b5c34ede0f70241218cc551621000dea\",\"name\":\"Reha Technology\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/","og_locale":"de_DE","og_type":"article","og_title":"Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology","og_description":"Deutschlandweit hat das Kinderzentrum Maulbronn jetzt den ersten Gang-Roboter einer v\u00f6llig neuen Generation in Betrieb genommen. Das Ger\u00e4t wurde speziell f\u00fcr gehbehinderte Kinder entwickelt und erm\u00f6glicht ganz neue therapeutische M\u00f6glichkeiten. Besuchen Sie die Webseite des Kinderzentrums Maulbronn und erfahren Sie mehr \u00fcber deren Behandlungsmethoden.","og_url":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/","og_site_name":"Reha Technology","article_publisher":"https:\/\/www.facebook.com\/rehatechnology\/","article_published_time":"2017-02-07T09:46:00+00:00","article_modified_time":"2019-04-26T14:25:42+00:00","author":"Reha Technology","twitter_card":"summary_large_image","twitter_creator":"@rehatechnology","twitter_site":"@rehatechnology","twitter_misc":{"Verfasst von":"Reha Technology"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#article","isPartOf":{"@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/"},"author":{"name":"Reha Technology","@id":"https:\/\/www.rehatechnology.com\/de\/#\/schema\/person\/b5c34ede0f70241218cc551621000dea"},"headline":"Laufen lernen in Maulbronn &#8211; Gang-Roboter unterst\u00fctzt gehbehinderte Kinder","datePublished":"2017-02-07T09:46:00+00:00","dateModified":"2019-04-26T14:25:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/"},"wordCount":59,"publisher":{"@id":"https:\/\/www.rehatechnology.com\/de\/#organization"},"articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/","url":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/","name":"Laufen lernen in Maulbronn - Gang-Roboter unterst\u00fctzt gehbehinderte Kinder &#8211; Reha Technology","isPartOf":{"@id":"https:\/\/www.rehatechnology.com\/de\/#website"},"datePublished":"2017-02-07T09:46:00+00:00","dateModified":"2019-04-26T14:25:42+00:00","breadcrumb":{"@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rehatechnology.com\/de\/laufen-lernen-in-maulbronn-gang-roboter-unterstuetzt-gehbehinderte-kinder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.rehatechnology.com\/de\/"},{"@type":"ListItem","position":2,"name":"Laufen lernen in Maulbronn &#8211; Gang-Roboter unterst\u00fctzt gehbehinderte Kinder"}]},{"@type":"WebSite","@id":"https:\/\/www.rehatechnology.com\/de\/#website","url":"https:\/\/www.rehatechnology.com\/de\/","name":"Reha Technology","description":"","publisher":{"@id":"https:\/\/www.rehatechnology.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rehatechnology.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.rehatechnology.com\/de\/#organization","name":"Reha Technology","url":"https:\/\/www.rehatechnology.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rehatechnology.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.rehatechnology.com\/wp-content\/uploads\/logo_reha_technology.svg","contentUrl":"https:\/\/www.rehatechnology.com\/wp-content\/uploads\/logo_reha_technology.svg","width":1,"height":1,"caption":"Reha Technology"},"image":{"@id":"https:\/\/www.rehatechnology.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rehatechnology\/","https:\/\/x.com\/rehatechnology","https:\/\/ch.linkedin.com\/company\/reha-technology-ag","https:\/\/www.youtube.com\/user\/rehatechnology"]},{"@type":"Person","@id":"https:\/\/www.rehatechnology.com\/de\/#\/schema\/person\/b5c34ede0f70241218cc551621000dea","name":"Reha Technology"}]}},"_links":{"self":[{"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/posts\/1164"}],"collection":[{"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/comments?post=1164"}],"version-history":[{"count":0,"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/posts\/1164\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/media?parent=1164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/categories?post=1164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rehatechnology.com\/de\/wp-json\/wp\/v2\/tags?post=1164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}